{"id":27103,"date":"2019-11-25T16:28:20","date_gmt":"2019-11-25T16:28:20","guid":{"rendered":"https:\/\/www.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1.jpg"},"modified":"2019-11-25T16:28:20","modified_gmt":"2019-11-25T16:28:20","slug":"refurb-eu-slim","status":"inherit","type":"attachment","link":"https:\/\/last.bluefinfitness.com\/de\/refurb-eu-slim\/","title":{"rendered":"refurb-eu-slim"},"author":309,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"smush":{"stats":{"percent":59.80354379496791,"bytes":388003,"size_before":648796,"size_after":260793,"time":0.88,"api_version":"1.0","lossy":true,"keep_exif":0},"sizes":{"thumbnail":{"percent":83.48,"bytes":31300,"size_before":37492,"size_after":6192,"time":0.02},"medium":{"percent":65.84,"bytes":36010,"size_before":54695,"size_after":18685,"time":0.04},"woocommerce_thumbnail":{"percent":52.6,"bytes":43805,"size_before":86044,"size_after":40786,"time":0.06},"woocommerce_single":{"percent":3.44,"bytes":966,"size_before":42239,"size_after":40786,"time":0.14},"woocommerce_gallery_thumbnail":{"percent":89.93,"bytes":30298,"size_before":33836,"size_after":3407,"time":0.06},"shop_catalog":{"percent":1.18,"bytes":319,"size_before":41273,"size_after":40786,"time":0.33},"shop_single":{"percent":0.41,"bytes":168,"size_before":40954,"size_after":40786,"time":0.04},"shop_thumbnail":{"percent":3.7,"bytes":131,"size_before":3538,"size_after":3407,"time":0.08},"full":{"percent":78.64,"bytes":242767,"size_before":308725,"size_after":65958,"time":0.11}},"webp_flag":"2019\/11\/refurb-eu-slim-1-150x150.jpg.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Bluefin \" srcset=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-300x300.jpg 300w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-150x150.jpg 150w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-500x500.jpg 500w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-100x100.jpg 100w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1.jpg 660w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":660,"height":660,"file":"2019\/11\/refurb-eu-slim-1.jpg","sizes":{"thumbnail":{"file":"refurb-eu-slim-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-150x150.jpg"},"medium":{"file":"refurb-eu-slim-1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-300x300.jpg"},"woocommerce_thumbnail":{"file":"refurb-eu-slim-1-500x500.jpg","width":500,"height":500,"uncropped":"1","mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-500x500.jpg"},"woocommerce_single":{"file":"refurb-eu-slim-1-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-500x500.jpg"},"woocommerce_gallery_thumbnail":{"file":"refurb-eu-slim-1-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-100x100.jpg"},"shop_catalog":{"file":"refurb-eu-slim-1-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-500x500.jpg"},"shop_single":{"file":"refurb-eu-slim-1-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-500x500.jpg"},"shop_thumbnail":{"file":"refurb-eu-slim-1-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1-100x100.jpg"},"full":{"file":"refurb-eu-slim-1.jpg","width":660,"height":660,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1"}},"post":null,"source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2019\/11\/refurb-eu-slim-1.jpg","_links":{"self":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/media\/27103"}],"collection":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/users\/309"}],"replies":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/comments?post=27103"}]}}