{"id":625998,"date":"2021-09-14T10:07:43","date_gmt":"2021-09-14T10:07:43","guid":{"rendered":"https:\/\/www.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png"},"modified":"2021-09-14T10:07:43","modified_gmt":"2021-09-14T10:07:43","slug":"de_vibration-plate-slim_a-images-01","status":"inherit","type":"attachment","link":"https:\/\/last.bluefinfitness.com\/de\/de_vibration-plate-slim_a-images-01\/","title":{"rendered":"DE_Vibration Plate Slim_A+ Images-01"},"author":309,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"smush":{"stats":{"percent":69.47436103520334,"bytes":531606,"size_before":765183,"size_after":233577,"time":3.5200000000000005,"api_version":"1.0","lossy":true,"keep_exif":0},"sizes":{"medium":{"percent":73.66,"bytes":28899,"size_before":39233,"size_after":10334,"time":0.07},"thumbnail":{"percent":76.56,"bytes":15850,"size_before":20704,"size_after":4854,"time":0.28},"medium_large":{"percent":75.5,"bytes":147277,"size_before":195074,"size_after":47797,"time":0.28},"woocommerce_thumbnail":{"percent":75,"bytes":68993,"size_before":91995,"size_after":23002,"time":0.49},"woocommerce_single":{"percent":0,"bytes":0,"size_before":23002,"size_after":23002,"time":0.08},"woocommerce_gallery_thumbnail":{"percent":75.23,"bytes":7903,"size_before":10505,"size_after":2602,"time":0.3},"shop_catalog":{"percent":0,"bytes":0,"size_before":23002,"size_after":23002,"time":0.9},"shop_single":{"percent":0,"bytes":0,"size_before":23002,"size_after":23002,"time":0.28},"shop_thumbnail":{"percent":0,"bytes":0,"size_before":2602,"size_after":2602,"time":0.02},"full":{"percent":78.16,"bytes":262684,"size_before":336064,"size_after":73380,"time":0.82}},"webp_flag":"2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-300x93.png.webp"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png'><img decoding=\"async\" width=\"300\" height=\"93\" src=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-300x93.png\" class=\"attachment-medium size-medium\" alt=\"Bluefin \" srcset=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-300x93.png 300w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-768x238.png 768w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-500x155.png 500w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png 970w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":970,"height":300,"file":"2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png","sizes":{"medium":{"file":"DE_Vibration-Plate-Slim_A-Images-01-300x93.png","width":300,"height":93,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-300x93.png"},"thumbnail":{"file":"DE_Vibration-Plate-Slim_A-Images-01-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-150x150.png"},"medium_large":{"file":"DE_Vibration-Plate-Slim_A-Images-01-768x238.png","width":768,"height":238,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-768x238.png"},"woocommerce_thumbnail":{"file":"DE_Vibration-Plate-Slim_A-Images-01-500x155.png","width":500,"height":155,"uncropped":true,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-500x155.png"},"woocommerce_single":{"file":"DE_Vibration-Plate-Slim_A-Images-01-500x155.png","width":500,"height":155,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-500x155.png"},"woocommerce_gallery_thumbnail":{"file":"DE_Vibration-Plate-Slim_A-Images-01-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-100x100.png"},"shop_catalog":{"file":"DE_Vibration-Plate-Slim_A-Images-01-500x155.png","width":500,"height":155,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-500x155.png"},"shop_single":{"file":"DE_Vibration-Plate-Slim_A-Images-01-500x155.png","width":500,"height":155,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-500x155.png"},"shop_thumbnail":{"file":"DE_Vibration-Plate-Slim_A-Images-01-100x100.png","width":100,"height":100,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01-100x100.png"},"full":{"file":"DE_Vibration-Plate-Slim_A-Images-01.png","width":970,"height":300,"mime_type":"image\/png","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2021\/09\/DE_Vibration-Plate-Slim_A-Images-01.png","_links":{"self":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/media\/625998"}],"collection":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/users\/309"}],"replies":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/de\/wp-json\/wp\/v2\/comments?post=625998"}]}}