{"id":659791,"date":"2024-03-06T18:23:50","date_gmt":"2024-03-06T18:23:50","guid":{"rendered":"https:\/\/www.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg"},"modified":"2024-03-06T18:23:50","modified_gmt":"2024-03-06T18:23:50","slug":"nl_ultra-light-vp_prem-a-images_09_premium-nav","status":"inherit","type":"attachment","link":"https:\/\/last.bluefinfitness.com\/nl\/?attachment_id=659791#main","title":{"rendered":"NL_Ultra-Light-VP_Prem A+ Images_09_Premium Nav"},"author":309,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"smush":{"stats":{"time":0.87,"bytes":429438,"percent":67.96,"size_before":631890,"size_after":202452,"lossy":1,"keep_exif":0,"api_version":"1.0"},"sizes":{"woocommerce_gallery_thumbnail":{"time":0.04,"bytes":58940,"percent":96.03,"size_before":61377,"size_after":2437},"woocommerce_thumbnail":{"time":0.06,"bytes":59380,"percent":78.04,"size_before":76087,"size_after":16707},"medium":{"time":0.04,"bytes":59803,"percent":62.85,"size_before":95159,"size_after":35356},"medium_large":{"time":0.05,"bytes":59857,"percent":63.78,"size_before":93843,"size_after":33986},"full":{"time":0.42,"bytes":73011,"percent":45.68,"size_before":159840,"size_after":86829},"woocommerce_single":{"time":0.12,"bytes":59380,"percent":78.04,"size_before":76087,"size_after":16707},"thumbnail":{"time":0.14,"bytes":59067,"percent":84.99,"size_before":69497,"size_after":10430}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg'><img decoding=\"async\" width=\"800\" height=\"328\" src=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-800x328.jpg\" class=\"attachment-medium size-medium\" alt=\"Bluefin \" srcset=\"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-800x328.jpg 800w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-768x315.jpg 768w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-500x205.jpg 500w, https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg 1464w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1464,"height":600,"file":"2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg","filesize":159840,"sizes":{"medium":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-800x328.jpg","width":800,"height":328,"filesize":95159,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-800x328.jpg"},"thumbnail":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-280x280.jpg","width":280,"height":280,"filesize":69497,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-280x280.jpg"},"medium_large":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-768x315.jpg","width":768,"height":315,"filesize":93843,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-768x315.jpg"},"woocommerce_thumbnail":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-500x205.jpg","width":500,"height":205,"filesize":76087,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-500x205.jpg"},"woocommerce_single":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-500x205.jpg","width":500,"height":205,"filesize":76087,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-500x205.jpg"},"woocommerce_gallery_thumbnail":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-100x100.jpg","width":100,"height":100,"filesize":61377,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav-100x100.jpg"},"full":{"file":"NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg","width":1464,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":652406,"source_url":"https:\/\/last.bluefinfitness.com\/wp-content\/uploads\/2023\/11\/NL_Ultra-Light-VP_Prem-A-Images_09_Premium-Nav.jpg","_links":{"self":[{"href":"https:\/\/last.bluefinfitness.com\/nl\/wp-json\/wp\/v2\/media\/659791"}],"collection":[{"href":"https:\/\/last.bluefinfitness.com\/nl\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/last.bluefinfitness.com\/nl\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/nl\/wp-json\/wp\/v2\/users\/309"}],"replies":[{"embeddable":true,"href":"https:\/\/last.bluefinfitness.com\/nl\/wp-json\/wp\/v2\/comments?post=659791"}]}}